{"id":425,"date":"2020-02-09T09:26:25","date_gmt":"2020-02-09T09:26:25","guid":{"rendered":"https:\/\/wp3.applion.hu\/?portfolio=golden-lemon"},"modified":"2022-10-06T07:35:53","modified_gmt":"2022-10-06T07:35:53","slug":"raiffeisen-scan-and-go","status":"publish","type":"portfolio","link":"https:\/\/applion.hu\/en\/portfolio\/raiffeisen-scan-and-go\/","title":{"rendered":"Raiffeisen Scan&#038;Go"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"425\" class=\"elementor elementor-425\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20bb7e81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20bb7e81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44344c72\" data-id=\"44344c72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54d2b782 elementor-widget elementor-widget-text-editor\" data-id=\"54d2b782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With the mobile application developed by us, the obligation to introduce a POS terminal can be dispensed with, since an entire business process can be followed with the help of the system. With the MyRaiffeisen application or the QR code according to the MNB standard, an immediate transfer order can be made, so the customer can make the payment from his mobile bank account after scanning the generated QR code.<\/p><p>Part of the innovation is also the software's transparent transaction history function, which can be used to track back and track the previous transfers and transactions of all users.<\/p><p>Technologies: <b>Android Kotlin, iOS Swift, Rx<\/b><\/p><p>With the application that can also generate the standard MNB or OTP Bank's own QR code, an immediate transfer request can be initiated, which also gives immediate feedback that the transfer has taken place.\u00a0<\/p><p>\u00a0<\/p><p><strong>Advantages of the application:<\/strong><\/p><ul><li>Can be operated cost-effectively from your own mobile device, without the need to build a card payment infrastructure<\/li><li>The application can also be managed by your company's employees<\/li><li>Millions of customers in Hungary can pay with a QR code, as the mobile banking applications of several domestic banks, including OTP, CIB, Takar\u00e9kbank, Gr\u00e1nitbank and Raiffeisen Bank, are already suitable for QR code payments,<\/li><li>You can also start a QR code payment and payment request<\/li><li>Customer payments are made immediately, while in the case of bank card payments it may take several days.<\/li><li>Affordable solution: there is no monthly fee and you only pay after successful transactions<\/li><li>Payment solution based on Hungarian National Bank standards<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0855580 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0855580\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bd07f0a\" data-id=\"bd07f0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b150598 elementor-widget elementor-widget-aux_image\" data-id=\"b150598\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au8ca9deb0\">\n    <div class=\"aux-media-hint-frame\">\n        <div class=\"aux-media-image\" >\n        \n            \n\n            \n            <img decoding=\"async\" src=\"https:\/\/applion.hu\/wp-content\/uploads\/2022\/08\/getItonGooglePlay_black.svg\" class=\"attachment-full size-full\" alt=\"Google play store button black\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a7b50c3\" data-id=\"a7b50c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fec569 elementor-widget elementor-widget-aux_image\" data-id=\"5fec569\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au9d235490\">\n    <div class=\"aux-media-hint-frame\">\n        <div class=\"aux-media-image\" >\n        \n            \n\n            \n            <img decoding=\"async\" src=\"https:\/\/applion.hu\/wp-content\/uploads\/2022\/08\/appStore_black.svg\" class=\"attachment-full size-full\" alt=\"App Store button black\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Az \u00e1ltalunk fejlesztett mobilalkalmaz\u00e1ssal kiv\u00e1lthat\u00f3 a POS termin\u00e1l bevezet\u00e9s\u00e9re vonatkoz\u00f3 k\u00f6telezetts\u00e9g, hiszen egy teljes \u00fcgymenet lek\u00f6vethet\u0151 a rendszer seg\u00edts\u00e9g\u00e9vel. A MyRaiffeisen applik\u00e1ci\u00f3val vagy az MNB szabv\u00e1ny szerinti QR k\u00f3ddal azonnali utal\u00e1si megb\u00edz\u00e1s k\u00e9sz\u00edthet\u0151, \u00edgy a v\u00e1s\u00e1rl\u00f3 a gener\u00e1lt QR k\u00f3d beolvas\u00e1sa ut\u00e1n v\u00e9grehajthatja a fizet\u00e9st saj\u00e1t mobilbanki fi\u00f3kj\u00e1b\u00f3l. Az \u00faj\u00edt\u00e1s r\u00e9sz\u00e9t k\u00e9pezi a szoftver transzparens [&hellip;]<\/p>\n","protected":false},"featured_media":3898,"menu_order":0,"template":"","meta":{"footnotes":""},"portfolio-cat":[28],"portfolio-tag":[27,26],"portfolio-filter":[36,35],"class_list":["post-425","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-cat-mobil-app-fejlesztes","portfolio-tag-android","portfolio-tag-ios","portfolio-filter-android","portfolio-filter-ios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raiffeisen Scan&amp;Go - Applion<\/title>\n<meta name=\"description\" content=\"A Scan&amp;Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/applion.hu\/en\/portfolio\/raiffeisen-scan-and-go\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raiffeisen Scan&amp;Go\" \/>\n<meta property=\"og:description\" content=\"A Scan&amp;Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/applion.hu\/en\/portfolio\/raiffeisen-scan-and-go\/\" \/>\n<meta property=\"og:site_name\" content=\"Applion\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TeamApplion\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T07:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/applion.hu\/wp-content\/uploads\/2022\/07\/Raiffeisen_1200x675.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Raiffeisen Scan&amp;Go\" \/>\n<meta name=\"twitter:description\" content=\"A Scan&amp;Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/\",\"url\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/\",\"name\":\"Raiffeisen Scan&Go - Applion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/applion.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/applion.hu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Raiffeisen_1200x675.jpg\",\"datePublished\":\"2020-02-09T09:26:25+00:00\",\"dateModified\":\"2022-10-06T07:35:53+00:00\",\"description\":\"A Scan&Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/#primaryimage\",\"url\":\"https:\\\/\\\/applion.hu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Raiffeisen_1200x675.jpg\",\"contentUrl\":\"https:\\\/\\\/applion.hu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Raiffeisen_1200x675.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Raiffeisen cover hun\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/raiffeisen-scan-and-go\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/applion.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolios\",\"item\":\"https:\\\/\\\/applion.hu\\\/portfolio\\\/all\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Raiffeisen Scan&#038;Go\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/applion.hu\\\/#website\",\"url\":\"https:\\\/\\\/applion.hu\\\/\",\"name\":\"Applion\",\"description\":\"Mobil megold\u00e1sok  21. sz\u00e1zadi v\u00e1llalatok sz\u00e1m\u00e1ra\",\"publisher\":{\"@id\":\"https:\\\/\\\/applion.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/applion.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/applion.hu\\\/#organization\",\"name\":\"Applion\",\"url\":\"https:\\\/\\\/applion.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/applion.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/applion.hu\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/applion_logoo.svg\",\"contentUrl\":\"https:\\\/\\\/applion.hu\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/applion_logoo.svg\",\"caption\":\"Applion\"},\"image\":{\"@id\":\"https:\\\/\\\/applion.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TeamApplion\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6NN4K2DeEb42L7hu1DoOWQ\\\/featured\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/27241120\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raiffeisen Scan&Go - Applion","description":"A Scan&Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/applion.hu\/en\/portfolio\/raiffeisen-scan-and-go\/","og_locale":"en_GB","og_type":"article","og_title":"Raiffeisen Scan&Go","og_description":"A Scan&Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.","og_url":"https:\/\/applion.hu\/en\/portfolio\/raiffeisen-scan-and-go\/","og_site_name":"Applion","article_publisher":"https:\/\/www.facebook.com\/TeamApplion","article_modified_time":"2022-10-06T07:35:53+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/applion.hu\/wp-content\/uploads\/2022\/07\/Raiffeisen_1200x675.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Raiffeisen Scan&Go","twitter_description":"A Scan&Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/","url":"https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/","name":"Raiffeisen Scan&Go - Applion","isPartOf":{"@id":"https:\/\/applion.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/#primaryimage"},"image":{"@id":"https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/#primaryimage"},"thumbnailUrl":"https:\/\/applion.hu\/wp-content\/uploads\/2022\/07\/Raiffeisen_1200x675.jpg","datePublished":"2020-02-09T09:26:25+00:00","dateModified":"2022-10-06T07:35:53+00:00","description":"A Scan&Go mobilapplik\u00e1ci\u00f3 seg\u00edts\u00e9g\u00e9vel gyorsan \u00e9s egyszer\u0171en int\u00e9zhet v\u00e1s\u00e1rl\u00e1si tranzakci\u00f3kat, a QR-k\u00f3dos azonnali fizet\u00e9si megold\u00e1ssal.","breadcrumb":{"@id":"https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/#primaryimage","url":"https:\/\/applion.hu\/wp-content\/uploads\/2022\/07\/Raiffeisen_1200x675.jpg","contentUrl":"https:\/\/applion.hu\/wp-content\/uploads\/2022\/07\/Raiffeisen_1200x675.jpg","width":1200,"height":675,"caption":"Raiffeisen cover hun"},{"@type":"BreadcrumbList","@id":"https:\/\/applion.hu\/portfolio\/raiffeisen-scan-and-go\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/applion.hu\/"},{"@type":"ListItem","position":2,"name":"Portfolios","item":"https:\/\/applion.hu\/portfolio\/all\/"},{"@type":"ListItem","position":3,"name":"Raiffeisen Scan&#038;Go"}]},{"@type":"WebSite","@id":"https:\/\/applion.hu\/#website","url":"https:\/\/applion.hu\/","name":"Applion","description":"Mobile solutions for 21st century companies","publisher":{"@id":"https:\/\/applion.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/applion.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/applion.hu\/#organization","name":"Applion","url":"https:\/\/applion.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/applion.hu\/#\/schema\/logo\/image\/","url":"https:\/\/applion.hu\/wp-content\/uploads\/2021\/11\/applion_logoo.svg","contentUrl":"https:\/\/applion.hu\/wp-content\/uploads\/2021\/11\/applion_logoo.svg","caption":"Applion"},"image":{"@id":"https:\/\/applion.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TeamApplion","https:\/\/www.youtube.com\/channel\/UC6NN4K2DeEb42L7hu1DoOWQ\/featured","https:\/\/www.linkedin.com\/company\/27241120"]}]}},"_links":{"self":[{"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/portfolio\/425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":25,"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/portfolio\/425\/revisions"}],"predecessor-version":[{"id":4724,"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/portfolio\/425\/revisions\/4724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/media\/3898"}],"wp:attachment":[{"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/media?parent=425"}],"wp:term":[{"taxonomy":"portfolio-cat","embeddable":true,"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/portfolio-cat?post=425"},{"taxonomy":"portfolio-tag","embeddable":true,"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/portfolio-tag?post=425"},{"taxonomy":"portfolio-filter","embeddable":true,"href":"https:\/\/applion.hu\/en\/wp-json\/wp\/v2\/portfolio-filter?post=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}